{"id":60992,"date":"2023-05-25T11:11:00","date_gmt":"2023-05-25T08:11:00","guid":{"rendered":"https:\/\/www.destinynums.com\/detskaya-matricza-sudby-zachem-rebenok-prishel-v-etot-mir-12\/"},"modified":"2025-04-23T20:43:09","modified_gmt":"2025-04-23T17:43:09","slug":"matriz-del-destino-infantil","status":"publish","type":"post","link":"https:\/\/www.destinynums.com\/es\/matriz-del-destino-infantil\/","title":{"rendered":"Matriz del Destino Infantil: \u00bfPara qu\u00e9 vino este ni\u00f1o al mundo? (12)"},"content":{"rendered":"\n<p>\u00bfHas o\u00eddo hablar de la <a href=\"https:\/\/www.destinynums.com\/#section-calculation\" data-type=\"URL\" data-id=\"https:\/\/www.destinynums.com\/#section-calculation\">Matriz del Destino Infantil<\/a>? El m\u00e9todo de Natalia Ladini de los \u201c22 Arcanos\u201d tambi\u00e9n incluye una secci\u00f3n dedicada a las matrices del destino de los ni\u00f1os. Pero, \u00bfqu\u00e9 es exactamente? \u00bfPara qu\u00e9 sirve? \u00bfY en qu\u00e9 se diferencia de la matriz personal?<\/p>\n\n\n\n<p>En este art\u00edculo, no solo te contaremos en qu\u00e9 consiste, sino que tambi\u00e9n exploraremos el prop\u00f3sito por el cual un ni\u00f1o llega a este mundo. Adem\u00e1s, incluiremos la interpretaci\u00f3n de cada energ\u00eda para que puedas entender el sentido de su llegada a esta vida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-700x467.png\" alt=\"Matriz del Destino Infantil: \u00bfPara qu\u00e9 vino este ni\u00f1o al mundo?\" class=\"wp-image-30302\" title=\"\" srcset=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-700x467.png 700w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-250x167.png 250w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-768x512.png 768w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-120x80.png 120w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55-600x400.png 600w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-55.png 960w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption class=\"wp-element-caption\">Matriz del Destino Infantil<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es la Matriz del Destino Infantil?<\/strong><\/h2>\n\n\n\n<p>La <a href=\"https:\/\/www.destinynums.com\/#section-childrens-matrix\" data-type=\"URL\" data-id=\"https:\/\/www.destinynums.com\/#section-childrens-matrix\">Matriz del Destino Infantil<\/a> se basa en la teor\u00eda de la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Reencarnaci%C3%B3n\" data-type=\"URL\" rel=\"nofollow noopener\" target=\"_blank\">reencarnaci\u00f3n<\/a>. Seg\u00fan esta teor\u00eda, cada persona llega al mundo con un prop\u00f3sito y una misi\u00f3n predeterminada antes de nacer. Esta matriz se representa por dos cuadrados superpuestos que contienen 12 zonas formadas por Arcanos.<\/p>\n\n\n\n<p>En esencia, la matriz infantil no se diferencia conceptualmente de la matriz personal. Sin embargo, puede ser una herramienta muy \u00fatil para que padres y educadores comprendan mejor a los ni\u00f1os: sus inclinaciones, talentos, y c\u00f3mo ayudarles a desarrollar su m\u00e1ximo potencial. Puedes calcularla usando <a href=\"https:\/\/www.destinynums.com\/#section-calculation\">nuestra calculadora gratuita.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfPor qu\u00e9 es importante saber por qu\u00e9 un ni\u00f1o lleg\u00f3 a esta vida?<\/strong><\/h2>\n\n\n\n<p>Conocer el prop\u00f3sito de vida de un ni\u00f1o puede ayudar a los padres a acompa\u00f1arlo mejor en su desarrollo, considerando sus necesidades y metas individuales. Tambi\u00e9n favorece la creaci\u00f3n de un v\u00ednculo m\u00e1s profundo y emp\u00e1tico, especialmente en momentos dif\u00edciles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-700x467.png\" alt=\"Matriz del Destino Infantil: \u00bfPara qu\u00e9 vino este ni\u00f1o al mundo?\" class=\"wp-image-30301\" title=\"\" srcset=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-700x467.png 700w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-250x167.png 250w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-768x512.png 768w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-120x80.png 120w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54-600x400.png 600w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-54.png 960w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption class=\"wp-element-caption\">Matriz del Destino Infantil<\/figcaption><\/figure>\n\n\n\n<p>Adem\u00e1s, saber cu\u00e1l es el prop\u00f3sito del ni\u00f1o puede ayudar a los padres a comprender mejor su rol dentro de la vida de su hijo. Por ejemplo, si el prop\u00f3sito es desarrollar su creatividad, los padres pueden apoyarlo con acceso a materiales art\u00edsticos o instrumentos musicales.<\/p>\n\n\n\n<p>Este conocimiento tambi\u00e9n puede ofrecer motivaci\u00f3n y claridad a los adultos, ayud\u00e1ndolos a contribuir conscientemente al desarrollo y felicidad de sus hijos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 zonas de la Matriz indican el prop\u00f3sito del ni\u00f1o?<\/strong><\/h2>\n\n\n\n<p>Para saber por qu\u00e9 un ni\u00f1o ha llegado a tu vida y qu\u00e9 misi\u00f3n trae su alma, hay que observar el Arcano del d\u00eda en que naci\u00f3. Ese d\u00eda representa el motivo por el cual ha elegido nacer dentro de tu familia.<\/p>\n\n\n\n<p>En la Matriz del Destino, el prop\u00f3sito del alma se encuentra en la zona llamada \u201cTarjeta de presentaci\u00f3n\u201d, ubicada al lado izquierdo de la l\u00ednea de la Tierra:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"526\" src=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-52.png\" alt=\"Matriz del Destino Infantil: \u00bfPara qu\u00e9 vino este ni\u00f1o al mundo?\" class=\"wp-image-30299\" title=\"\" srcset=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-52.png 534w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-52-250x246.png 250w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-52-120x118.png 120w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-52-100x100.png 100w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><figcaption class=\"wp-element-caption\">Matriz del Destino Infantil<\/figcaption><\/figure>\n\n\n\n<p>Esta energ\u00eda est\u00e1 influenciada por el chakra de la corona, Sahasrara. Por lo tanto, afectar\u00e1 directamente el pensamiento del ni\u00f1o y su manera de tomar decisiones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Interpretaci\u00f3n de las energ\u00edas: \u00bfPor qu\u00e9 vino este ni\u00f1o al mundo?<\/strong><\/h2>\n\n\n\n<p>Despu\u00e9s de calcular la matriz con la herramienta, es importante interpretar el Arcano de la \u201cTarjeta de presentaci\u00f3n\u201d para comprender el prop\u00f3sito del ni\u00f1o. A continuaci\u00f3n, te compartimos el significado de cada Arcano:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El Mago \u2014 vino a despertar la creatividad en los dem\u00e1s y ense\u00f1arles a crear su realidad.<\/li>\n\n\n\n<li>La Sacerdotisa \u2014 vino a unir a las personas mediante la palabra y manifestar su propio mundo.<\/li>\n\n\n\n<li>La Emperatriz \u2014 lleg\u00f3 a brindar confort y abundancia, aprendiendo a canalizar su energ\u00eda de forma constructiva.<\/li>\n\n\n\n<li>El Emperador \u2014 vino a desarrollar responsabilidad, fijar metas y alcanzarlas, sobre todo en el \u00e1mbito material.<\/li>\n\n\n\n<li>El Hierofante \u2014 tiene la misi\u00f3n de fortalecer los valores familiares y brindar confianza a los dem\u00e1s.<\/li>\n\n\n\n<li>Los Enamorados \u2014 vino a aprender a amar incondicionalmente y aceptarse plenamente.<\/li>\n\n\n\n<li>El Carro \u2014 su tarea es asumir el control de su vida y actuar con decisi\u00f3n.<\/li>\n\n\n\n<li>La Justicia \u2014 vino a sanar su karma, entendiendo las causas y consecuencias, y organizar su entorno.<\/li>\n\n\n\n<li>El Ermita\u00f1o \u2014 vino a adquirir sabidur\u00eda y convertirse en gu\u00eda espiritual para los dem\u00e1s.<\/li>\n\n\n\n<li>La Rueda de la Fortuna \u2014 vino a disfrutar de la vida y fluir con ella, aportando ligereza a quienes le rodean.<\/li>\n\n\n\n<li>La Fuerza \u2014 vino a fijarse metas y superarlas a pesar de los obst\u00e1culos.<\/li>\n\n\n\n<li>El Colgado \u2014 vino a ayudar a otros sin sacrificar su autenticidad ni principios.<\/li>\n\n\n\n<li>La Muerte \u2014 vino a vencer miedos, asumir riesgos y vivir con intensidad.<\/li>\n\n\n\n<li>La Templanza \u2014 vino a comprender que ya tiene todo lo que necesita y a aceptar que todo llega a su tiempo.<\/li>\n\n\n\n<li>El Diablo \u2014 vino a crear abundancia sin dejarse dominar por la tentaci\u00f3n, desarrollando un entusiasmo sano por la vida.<\/li>\n\n\n\n<li>La Torre \u2014 vino a superar desaf\u00edos, iniciar de cero y construir nuevos cimientos para inspirar a los dem\u00e1s.<\/li>\n\n\n\n<li>La Estrella \u2014 vino a brillar, superar sus miedos y convertirse en ejemplo para otros.<\/li>\n\n\n\n<li>La Luna \u2014 vino a desarrollar su intuici\u00f3n, distinguir lo verdadero de lo falso y liberar sus temores.<\/li>\n\n\n\n<li>El Sol \u2014 vino a brindar calidez, ganarse el respeto de los dem\u00e1s y vivir en plenitud.<\/li>\n\n\n\n<li>El Juicio \u2014 vino a luchar por la justicia, encontrar su vocaci\u00f3n y evaluar objetivamente cada situaci\u00f3n.<\/li>\n\n\n\n<li>El Mundo \u2014 vino a pensar en grande, ser abierto y responsable, y encontrar armon\u00eda interior.<\/li>\n\n\n\n<li>El Loco \u2014 vino a ser aut\u00e9ntico, dejar atr\u00e1s el rol de v\u00edctima y asumir responsabilidad por sus actos.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-700x467.png\" alt=\"Matriz del Destino Infantil: \u00bfPara qu\u00e9 vino este ni\u00f1o al mundo?\" class=\"wp-image-30300\" title=\"\" srcset=\"https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-700x467.png 700w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-250x167.png 250w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-768x512.png 768w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-120x80.png 120w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53-600x400.png 600w, https:\/\/www.destinynums.com\/wp-content\/uploads\/2023\/05\/image-53.png 960w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong><\/h2>\n\n\n\n<p>La Matriz del Destino Infantil revela por qu\u00e9 un ni\u00f1o ha llegado a esta vida. Para descubrirlo, calcula su <a href=\"https:\/\/www.destinynums.com\/#section-childrens-matrix\" data-type=\"URL\" data-id=\"https:\/\/www.destinynums.com\/#section-childrens-matrix\">matriz con nuestra calculadora<\/a>, identifica su \u201ctarjeta de presentaci\u00f3n\u201d y consulta su interpretaci\u00f3n aqu\u00ed mismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHas o\u00eddo hablar de la Matriz del Destino Infantil? El m\u00e9todo de Natalia Ladini de los \u201c22 Arcanos\u201d tambi\u00e9n incluye una secci\u00f3n dedicada a las matrices del destino de los ni\u00f1os. Pero, \u00bfqu\u00e9 es exactamente? \u00bfPara qu\u00e9 sirve? \u00bfY en qu\u00e9 se diferencia de la matriz personal? En este art\u00edculo, no solo te contaremos en [&hellip;]<\/p>\n","protected":false},"author":12338,"featured_media":60994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-60992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/posts\/60992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/users\/12338"}],"replies":[{"embeddable":true,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/comments?post=60992"}],"version-history":[{"count":1,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/posts\/60992\/revisions"}],"predecessor-version":[{"id":61030,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/posts\/60992\/revisions\/61030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/media\/60994"}],"wp:attachment":[{"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/media?parent=60992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/categories?post=60992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.destinynums.com\/es\/wp-json\/wp\/v2\/tags?post=60992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}